{"id":599,"date":"2022-02-06T16:33:37","date_gmt":"2022-02-06T15:33:37","guid":{"rendered":"http:\/\/marjorie-bobet-psychanalyste.fr\/?p=599"},"modified":"2026-02-25T13:41:20","modified_gmt":"2026-02-25T12:41:20","slug":"anxiete","status":"publish","type":"post","link":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/2022\/02\/06\/anxiete\/","title":{"rendered":"Comprendre l&rsquo;Anxi\u00e9t\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"599\" class=\"elementor elementor-599\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e704085 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"e704085\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2c785035 exad-glass-effect-no exad-sticky-section-no\" data-id=\"2c785035\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26ba5367 elementor-hidden-mobile exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"26ba5367\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Sans-titre-4-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-47\" alt=\"Psychanalyste Castrie\" srcset=\"https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Sans-titre-4-1-150x150.png 150w, https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Sans-titre-4-1-300x300.png 300w, https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Sans-titre-4-1-768x768.png 768w, https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Sans-titre-4-1.png 842w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-30b85095 exad-glass-effect-no exad-sticky-section-no\" data-id=\"30b85095\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42408fcd elementor-hidden-mobile exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"42408fcd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPsychanalyste &#8211; Praticienne PNL<\/br>\nEn cabinet ou en t\u00e9l\u00e9consultation\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2e48877a exad-glass-effect-no exad-sticky-section-no\" data-id=\"2e48877a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3857031d elementor-align-right elementor-mobile-align-left exad-sticky-section-no exad-glass-effect-no elementor-invisible elementor-widget elementor-widget-button\" data-id=\"3857031d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"https:\/\/www.keldoc.com\/psychanalyste\/castries-34160\/marjorie-bobet?cabinet=26780\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RDV<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7c35fb20 exad-glass-effect-no exad-sticky-section-no\" data-id=\"7c35fb20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-486d25e7 hfe-menu-item-flex-start hfe-menu-item-space-between hfe-submenu-icon-arrow hfe-link-redirect-child exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-navigation-menu\" data-id=\"486d25e7\" data-element_type=\"widget\" data-settings=\"{&quot;hamburger_align_mobile&quot;:&quot;right&quot;,&quot;hamburger_menu_align_mobile&quot;:&quot;flex-start&quot;,&quot;width_flyout_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:365,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:34,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:27,&quot;sizes&quot;:[]},&quot;hamburger_align&quot;:&quot;center&quot;,&quot;hamburger_menu_align&quot;:&quot;space-between&quot;,&quot;width_flyout_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;width_flyout_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_flyout_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;padding_flyout_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_flyout_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_top_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_top_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_top_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;close_flyout_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;close_flyout_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;close_flyout_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"hfe-nav-menu__toggle elementor-clickable hfe-flyout-trigger\" tabindex=\"0\" role=\"button\" aria-label=\"Menu Toggle\">\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" tabindex=\"0\" class=\"fas fa-bars\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<div class=\"hfe-flyout-wrapper\" >\n\t\t\t\t<div class=\"hfe-flyout-overlay elementor-clickable\"><\/div>\n\t\t\t\t<div class=\"hfe-flyout-container\">\n\t\t\t\t\t<div id=\"hfe-flyout-content-id-486d25e7\" class=\"hfe-side hfe-flyout-right hfe-flyout-open\" data-layout=\"right\" data-flyout-type=\"normal\">\n\t\t\t\t\t\t<div class=\"hfe-flyout-content push\">\n\t\t\t\t\t\t\t<nav >\n\t\t\t\t\t\t\t\t<ul id=\"menu-1-486d25e7\" class=\"hfe-nav-menu\"><li id=\"menu-item-471\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home parent hfe-creative-menu\"><a href=\"https:\/\/marjorie-bobet-psychanalyste.fr\/\" class = \"hfe-menu-item\">Accueil<\/a><\/li>\n<li id=\"menu-item-194\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/ethique\/\" class = \"hfe-menu-item\">Ethique<\/a><\/li>\n<li id=\"menu-item-195\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/blog\/\" class = \"hfe-menu-item\">Blog<\/a><\/li>\n<li id=\"menu-item-193\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/contact\/\" class = \"hfe-menu-item\">Contact<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t<\/nav>\n\t\t\t\t\t\t\t<div class=\"elementor-clickable hfe-flyout-close\" tabindex=\"0\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" tabindex=\"0\" class=\"far fa-window-close\"><\/i>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad6e6fa elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"ad6e6fa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-94ab5c3 exad-glass-effect-no exad-sticky-section-no\" data-id=\"94ab5c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c728584 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"c728584\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"508\" height=\"339\" src=\"https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Phobie.jpg\" class=\"attachment-large size-large wp-image-57\" alt=\"Anxiete\" srcset=\"https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Phobie.jpg 508w, https:\/\/marjorie-bobet-psychanalyste.fr\/wp-content\/uploads\/2022\/01\/Phobie-300x200.jpg 300w\" sizes=\"(max-width: 508px) 100vw, 508px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-944f87e exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"944f87e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des sentiments de peur, de crainte ou encore d\u2019inqui\u00e9tude ? L\u2019anxi\u00e9t\u00e9 est une r\u00e9ponse \u00e0 une <b>situation stressante<\/b>, si celle-ci devient excessive elle est appel\u00e9e \u00ab <b>trouble de l\u2019anxi\u00e9t\u00e9<\/b> \u00bb. L&rsquo;anxi\u00e9t\u00e9 peut se manifester sous forme <b>d&rsquo;attaques<\/b>, <b>crises <\/b>de panique, <b>phobies <\/b>ou encore de <b>troubles <\/b>anxieux g\u00e9n\u00e9ralis\u00e9s.<\/p><h3>Qu&rsquo;est-ce que l&rsquo;anxi\u00e9t\u00e9 ?<\/h3><p>L&rsquo;anxi\u00e9t\u00e9 est un <b>m\u00e9canisme de d\u00e9fense<\/b> universel qui nous maintient en alerte face aux situations que nous consid\u00e9rons mena\u00e7antes. Sa fonction est de mobiliser l&rsquo;organisme pour qu&rsquo;il reste pr\u00eat \u00e0 intervenir face aux menaces. N\u00e9anmoins une anxi\u00e9t\u00e9 <b>excessive <\/b>peut provoquer des troubles anxieux, une attaque d&rsquo;anxi\u00e9t\u00e9 alors, difficile \u00e0 g\u00e9rer. Elle peut \u00e9galement amener \u00e0 un trouble anxieux g\u00e9n\u00e9ralis\u00e9 (TAG) qui se traduit essentiellement par une anxi\u00e9t\u00e9 quasi permanente ou des sympt\u00f4mes anxieux non sp\u00e9cifiques.<\/p><p>Le trouble anxieux est une des <b>maladies <\/b>mentales les plus fr\u00e9quentes qui se soigne gr\u00e2ce \u00e0 une prise en charge adapt\u00e9e. L&rsquo;anxi\u00e9t\u00e9 ponctuelle est \u00e9videmment normale si elle n&rsquo;affecte pas gravement notre qualit\u00e9 de vie. Les troubles d&rsquo;anxi\u00e9t\u00e9 peuvent aller jusqu&rsquo;\u00e0 perturber le quotidien de la personne et amener \u00e0 des crises d&rsquo;angoisse.<\/p><h3>Quelles sont les causes de l&rsquo;anxi\u00e9t\u00e9 ?<\/h3><p>Il n&rsquo;est pas toujours \u00e9vident de conna\u00eetre ce qui va d\u00e9clencher le trouble anxieux chez certaines personnes. Il existe un grand nombre de facteurs pouvant en \u00eatre la cause qu&rsquo;ils soient biologiques ou psychologiques.<\/p><p>Pour savoir d&rsquo;o\u00f9 vient cette anxi\u00e9t\u00e9, il faut s&rsquo;interroger sur ce qui pourrait l&rsquo;avoir caus\u00e9 :<\/p><ul><li>\u00a0\u00a0\u00a0 un \u00e9v\u00e9nement stressant voire traumatisant<\/li><li>\u00a0\u00a0\u00a0 des ant\u00e9c\u00e9dents familiaux de troubles anxieux<\/li><li>\u00a0\u00a0\u00a0 un \u00e9v\u00e9nement difficile v\u00e9cu dans l&rsquo;enfance<\/li><li>\u00a0\u00a0\u00a0 la consommation de caf\u00e9, d&rsquo;alcool, de m\u00e9dicaments ou de substances illicites.<\/li><li>\u00a0\u00a0\u00a0 l&rsquo;arr\u00eat de tabac<\/li><li>\u00a0\u00a0\u00a0 une an\u00e9mie ou des troubles de la thyro\u00efde<\/li><li>\u00a0\u00a0\u00a0 tout probl\u00e8me m\u00e9dical ou psychique, etc.<\/li><\/ul><h3>Quels sont les sympt\u00f4mes de l&rsquo;anxi\u00e9t\u00e9 ?<\/h3><p>L&rsquo;anxi\u00e9t\u00e9 peut se manifester graduellement en passant par diff\u00e9rents niveaux d&rsquo;affection. Face aux sympt\u00f4mes d&rsquo;une anxi\u00e9t\u00e9 plus importante, la douleur devient un v\u00e9ritable sympt\u00f4me physique \u00e0 cause de la forte pression qu&rsquo;elle vous apporte au quotidien. Peu \u00e0 peu, il arrive que les personnes commencent \u00e0 \u00e9prouver l&rsquo;anxi\u00e9t\u00e9 de l&rsquo;anxi\u00e9t\u00e9. Cela provoque ainsi une crainte de l&rsquo;arriv\u00e9e de chaque sympt\u00f4me qui se renforce une pens\u00e9e obsessionnelle\u00a0:\u00a0<\/p><ul><li>Les sympt\u00f4mes affectifs tels que la peur, l&rsquo;inqui\u00e9tude permanente, l&rsquo;irritabilit\u00e9, la crise de panique.<\/li><li>Les sympt\u00f4mes physiologiques : douleurs dans la poitrine comme une oppression thoracique, des difficult\u00e9s respiratoires, des douleurs intercostales, de la tachycardie en sentant les palpitations cardiaques plus fortes, des engourdissements, des sensations de malaise, de t\u00eate qui tourne, des fourmillements dans les mains, des bouff\u00e9es de chaleur, des naus\u00e9es, une transpiration excessive, des douleurs intercostales \u00e0 cause du stress g\u00e9n\u00e9r\u00e9 par l&rsquo;anxi\u00e9t\u00e9, de l&rsquo;insomnie, des tremblements nerveux, etc.<\/li><li>Les sympt\u00f4mes cognitifs par les difficult\u00e9s de concentration, la peur de devenir fou, la perte de contr\u00f4le, etc.<\/li><li>Les sympt\u00f4mes comportementaux qui se traduisent par une grande agitation, l&rsquo;\u00e9vitement des situations qui provoquent votre anxi\u00e9t\u00e9, une attitude crisp\u00e9e, etc.<\/li><\/ul><h3>Quelles sont les cons\u00e9quences de l&rsquo;anxi\u00e9t\u00e9 ?<\/h3><p>Les crises d&rsquo;anxi\u00e9t\u00e9 peuvent avoir de lourdes cons\u00e9quences sur notre organisme et g\u00e9n\u00e9rer perte ou prise de poids mais aussi d\u00e9mangeaisons, tensions nerveuses, \u00e9tourdissements, sueurs nocturnes, fatigue chronique, etc.<\/p><p>L&rsquo;anxi\u00e9t\u00e9 provoque un <b>\u00e9tat de peur chronique<\/b> et peut \u00e9galement avoir un impact important sur la perte de confiance en soi. Les cons\u00e9quences physiques jouent un r\u00f4le primordial dans la perception de l&rsquo;anxi\u00e9t\u00e9 sur le quotidien en entra\u00eenant la personne dans ce cercle vicieux.<\/p><h3>Comment soigner l&rsquo;anxi\u00e9t\u00e9 ?<\/h3><p>Des s\u00e9ances de <b>psychanalyses <\/b>nous permettent de remonter \u00e0 l\u2019origine de ce trouble afin d\u2019en <b>att\u00e9nuer <\/b>les effets.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Psychanalyste &#8211; Praticienne PNL En cabinet ou en t\u00e9l\u00e9consultation RDV Accueil Ethique Blog Contact Des sentiments de peur, de crainte ou encore d\u2019inqui\u00e9tude ? L\u2019anxi\u00e9t\u00e9 est une r\u00e9ponse \u00e0 une situation stressante, si celle-ci devient excessive elle est appel\u00e9e \u00ab trouble de l\u2019anxi\u00e9t\u00e9 \u00bb. L&rsquo;anxi\u00e9t\u00e9 peut se manifester sous forme d&rsquo;attaques, crises de panique, phobies [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"off","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[]},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/posts\/599"}],"collection":[{"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":33,"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"predecessor-version":[{"id":1672,"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/posts\/599\/revisions\/1672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/media\/57"}],"wp:attachment":[{"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marjorie-bobet-psychanalyste.fr\/index.php\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}